{"id":214,"count":9,"description":"","link":"https:\/\/passadicosdomondego.net\/en\/tag\/serra-da-estrela-en\/","name":"Serra da Estrela","slug":"serra-da-estrela-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v16.6 (Yoast SEO v16.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Serra da Estrela Archives - Passadi\u00e7os do Mondego<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/passadicosdomondego.net\/en\/tag\/serra-da-estrela-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Serra da Estrela Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/passadicosdomondego.net\/en\/tag\/serra-da-estrela-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Passadi\u00e7os do Mondego\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#website\",\"url\":\"https:\/\/passadicosdomondego.net\/es\/\",\"name\":\"Passadi\\u00e7os do Mondego\",\"description\":\"Natureza na Guarda e Serra da Estrela\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/passadicosdomondego.net\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/passadicosdomondego.net\/en\/tag\/serra-da-estrela-en\/#webpage\",\"url\":\"https:\/\/passadicosdomondego.net\/en\/tag\/serra-da-estrela-en\/\",\"name\":\"Serra da Estrela Archives - Passadi\\u00e7os do Mondego\",\"isPartOf\":{\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/passadicosdomondego.net\/en\/tag\/serra-da-estrela-en\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/passadicosdomondego.net\/en\/tag\/serra-da-estrela-en\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/passadicosdomondego.net\/en\/tag\/serra-da-estrela-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/passadicosdomondego.net\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Serra da Estrela\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/passadicosdomondego.net\/en\/wp-json\/wp\/v2\/tags\/214"}],"collection":[{"href":"https:\/\/passadicosdomondego.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/passadicosdomondego.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/passadicosdomondego.net\/en\/wp-json\/wp\/v2\/posts?tags=214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}