{"id":185,"count":2,"description":"","link":"https:\/\/passadicosdomondego.net\/fr\/category\/laine\/","name":"Laine","slug":"laine","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v16.6 (Yoast SEO v16.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Laine Archives - Passadi\u00e7os do Mondego<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/passadicosdomondego.net\/fr\/category\/laine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Laine Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/passadicosdomondego.net\/fr\/category\/laine\/\" \/>\n<meta property=\"og:site_name\" content=\"Passadi\u00e7os do Mondego\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#website\",\"url\":\"https:\/\/passadicosdomondego.net\/es\/\",\"name\":\"Passadi\\u00e7os do Mondego\",\"description\":\"Natureza na Guarda e Serra da Estrela\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/passadicosdomondego.net\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/passadicosdomondego.net\/fr\/category\/laine\/#webpage\",\"url\":\"https:\/\/passadicosdomondego.net\/fr\/category\/laine\/\",\"name\":\"Laine Archives - Passadi\\u00e7os do Mondego\",\"isPartOf\":{\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/passadicosdomondego.net\/fr\/category\/laine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/passadicosdomondego.net\/fr\/category\/laine\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/passadicosdomondego.net\/fr\/category\/laine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/passadicosdomondego.net\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laine\"}]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/categories\/185"}],"collection":[{"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/posts?categories=185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}