{"id":16808,"date":"2021-10-14T04:01:13","date_gmt":"2021-10-14T04:01:13","guid":{"rendered":"http:\/\/passadicosdomondego.net\/?p=16808"},"modified":"2021-10-14T04:01:13","modified_gmt":"2021-10-14T04:01:13","slug":"parc-archeologique-de-la-vale-do-coa","status":"publish","type":"post","link":"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/","title":{"rendered":"Parc Arch\u00e9ologique de la Vale do C\u00f4a"},"content":{"rendered":"<p>Vous avez certainement entendu parler des gravures de Foz C\u00f4a, mais vous n&rsquo;avez jamais eu le privil\u00e8ge de conna\u00eetre de pr\u00e8s ce patrimoine de l&rsquo;humanit\u00e9. Le parc arch\u00e9ologique de Vale do C\u00f4a est situ\u00e9 \u00e0 Foz C\u00f4a, dans le quartier de Guarda et \u00e0 moins d&rsquo;une heure de route des Passadi\u00e7os do Mondego. Il est vrai qu&rsquo;elle n&rsquo;est plus l\u00e0, mais la vall\u00e9e de la C\u00f4a m\u00e9rite une visite, non seulement pour sa beaut\u00e9 paysag\u00e8re mais aussi pour tout le patrimoine arch\u00e9ologique que vous y trouverez.<\/p>\n<p>L&rsquo;art rupestre se r\u00e9partit selon deux axes principaux : le C\u00f4a et le Douro. Au total, plus de 1200 roches sont connues pour \u00eatre grav\u00e9es dans 80 endroits diff\u00e9rents, principalement du pal\u00e9olithique, mais aussi de l&rsquo;\u00e2ge du fer et de la p\u00e9riode historique.<\/p>\n<p>Une visite au Mus\u00e9e C\u00f4a permet de cadrer et de recr\u00e9er toute l&rsquo;histoire du lieu. Ensuite, vous pouvez faire l&rsquo;une des diff\u00e9rentes visites disponibles au parc arch\u00e9ologique de Vale do C\u00f4a pour voir, vivre, les gravures d&rsquo;art rupestre.<\/p>\n<p>Veuillez noter que les visites du parc arch\u00e9ologique de la vall\u00e9e de C\u00f4a doivent \u00eatre programm\u00e9es \u00e0 l&rsquo;avance pour garantir l&rsquo;acc\u00e8s \u00e0 une visite. R\u00e9servez votre visite sur le site <a href=\"https:\/\/arte-coa.pt\">https:\/\/arte-coa.pt<\/a> et obtenez toutes les informations dont vous avez besoin pour votre visite.<\/p>\n<p>Si vous envisagez de visiter le parc et les gravures rupestres, ne visitez pas le site sans rendez-vous pr\u00e9alable, car vous ne pourrez probablement pas obtenir de billet le jour de la visite.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous avez certainement entendu parler des gravures de Foz C\u00f4a, mais vous n&rsquo;avez jamais eu le privil\u00e8ge de conna\u00eetre de pr\u00e8s ce patrimoine de l&rsquo;humanit\u00e9. Le parc arch\u00e9ologique de Vale do C\u00f4a est situ\u00e9 \u00e0 Foz C\u00f4a, dans le quartier [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":16804,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[161,188],"tags":[196],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v16.6 (Yoast SEO v16.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Parc Arch\u00e9ologique de la Vale do C\u00f4a - Passadi\u00e7os do Mondego<\/title>\n<meta name=\"description\" content=\"Le parc arch\u00e9ologique de Vale do C\u00f4a est situ\u00e9 \u00e0 Foz C\u00f4a et doit \u00eatre r\u00e9serv\u00e9 pour une visite. R\u00e9servez et obtenez des billets.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parc Arch\u00e9ologique de la Vale do C\u00f4a\" \/>\n<meta property=\"og:description\" content=\"Le parc arch\u00e9ologique de Vale do C\u00f4a est situ\u00e9 \u00e0 Foz C\u00f4a et doit \u00eatre r\u00e9serv\u00e9 pour une visite. R\u00e9servez et obtenez des billets.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/\" \/>\n<meta property=\"og:site_name\" content=\"Passadi\u00e7os do Mondego\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T04:01:13+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/passadicosdomondego.net\/wp-content\/uploads\/2021\/10\/foz-coa.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1650\" \/>\n\t<meta property=\"og:image:height\" content=\"1100\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#website\",\"url\":\"https:\/\/passadicosdomondego.net\/es\/\",\"name\":\"Passadi\\u00e7os do Mondego\",\"description\":\"Natureza na Guarda e Serra da Estrela\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/passadicosdomondego.net\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/passadicosdomondego.net\/wp-content\/uploads\/2021\/10\/foz-coa.jpg\",\"contentUrl\":\"https:\/\/passadicosdomondego.net\/wp-content\/uploads\/2021\/10\/foz-coa.jpg\",\"width\":1650,\"height\":1100,\"caption\":\"Parque Arqueol\\u00f3gico do Vale do C\\u00f4a\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/#webpage\",\"url\":\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/\",\"name\":\"Parc Arch\\u00e9ologique de la Vale do C\\u00f4a - Passadi\\u00e7os do Mondego\",\"isPartOf\":{\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/#primaryimage\"},\"datePublished\":\"2021-10-14T04:01:13+00:00\",\"dateModified\":\"2021-10-14T04:01:13+00:00\",\"author\":{\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#\/schema\/person\/a4a1272bb58a8a9dd64b775ef7cd1120\"},\"description\":\"Le parc arch\\u00e9ologique de Vale do C\\u00f4a est situ\\u00e9 \\u00e0 Foz C\\u00f4a et doit \\u00eatre r\\u00e9serv\\u00e9 pour une visite. R\\u00e9servez et obtenez des billets.\",\"breadcrumb\":{\"@id\":\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/passadicosdomondego.net\/fr\/parc-archeologique-de-la-vale-do-coa\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/passadicosdomondego.net\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parc Arch\\u00e9ologique de la Vale do C\\u00f4a\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#\/schema\/person\/a4a1272bb58a8a9dd64b775ef7cd1120\",\"name\":\"pmondego\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/passadicosdomondego.net\/es\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/15492b5fad392fe1cb55e949f1b1fea6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/15492b5fad392fe1cb55e949f1b1fea6?s=96&d=mm&r=g\",\"caption\":\"pmondego\"},\"sameAs\":[\"http:\/\/passadicosdomondego.net\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","_links":{"self":[{"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/posts\/16808"}],"collection":[{"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/comments?post=16808"}],"version-history":[{"count":1,"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/posts\/16808\/revisions"}],"predecessor-version":[{"id":16812,"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/posts\/16808\/revisions\/16812"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/media\/16804"}],"wp:attachment":[{"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/media?parent=16808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/categories?post=16808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/passadicosdomondego.net\/fr\/wp-json\/wp\/v2\/tags?post=16808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}